{"id":5244,"date":"2018-05-27T00:25:31","date_gmt":"2018-05-26T22:25:31","guid":{"rendered":"http:\/\/circoloculturalesanfrancesco.org\/?p=5244"},"modified":"2018-05-27T10:42:07","modified_gmt":"2018-05-27T08:42:07","slug":"vibrava-lideale-della-nonviolenza","status":"publish","type":"post","link":"https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/","title":{"rendered":"&#8230;vibrava l&#8217;ideale della nonviolenza"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/5244?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Visualizza PDF\" \/><\/a><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/5244?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Stampa contenuto\" \/><\/a><\/div><p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-5199\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-212x300.jpg 212w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-768x1086.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-724x1024.jpg 724w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-71x100.jpg 71w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/All-Cops-are-Bastards-25.05.2018-Poster-54x77.jpg 54w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>In ogni scelta non dobbiamo mai lasciarci guidare dalla logica della violenza, e neppure da quella del taglione, cio\u00e8 dell&#8217;\u00abocchio per occhio\u00bb e \u00abdente per dente\u00bb. Non ne hanno avuto dubbi i presenti alla <a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/event\/all-cops-are-bastards-9a-serata-cinematografica-con-cocktail-126\/\">9\u00aa Serata cinematografica<\/a>, che si \u00e8 svolta venerd\u00ec 25 maggio 2018 presso la chiesa \u00abSacro Cuore\u00bb di Catanzaro Lido. La Serata si \u00e8 aperta \u2212 \u00e8 vero \u2212 con il videoclip \u00ab<a href=\"https:\/\/youtu.be\/VkaYnms4xSc\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=it&amp;q=https:\/\/youtu.be\/VkaYnms4xSc&amp;source=gmail&amp;ust=1527458190222000&amp;usg=AFQjCNFSAvh7RbNIesw0JsuNHqIv9IP1ig\"><strong>Giocondit\u00e0<\/strong><\/a>\u00bb, la marcia militare eseguita dalla banda della Polizia di Stato&nbsp;in Piazza del Duomo di Milano, ma si \u00e8 conclusa con il filmato&nbsp;<strong><a href=\"https:\/\/youtu.be\/TTBCoRjeTXo\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=it&amp;q=https:\/\/youtu.be\/TTBCoRjeTXo&amp;source=gmail&amp;ust=1527458190222000&amp;usg=AFQjCNFI8aZzAhwJAgs-QnGrPd23Vb9RPg\">AmandoTi<\/a><\/strong>\u00bb realizzato dai ragazzi disabili del Centro riabilitativo \u00abNuova Itaca\u00bb di San Pietro in Lama (Lecce) con la collaborazione di artisti e musicisti del Salento, in occasione della giornata contro la violenza sulle donne. Nell&#8217;aria&nbsp;vibrava l&#8217;ideale della nonviolenza, della comunione, della fratellanza. Con il film \u00abAll Cops are Bastards\u00bb (Tutti i poliziotti sono bastardi) del regista Stefano Sollima, ideato all\u2019interno della 6\u00aa edizione del <em>Cine<\/em>Circolo dal motto: \u00ab<strong>I giovani con \u2018sorella\u2019-\u2018madre\u2019 Terra per immagini<\/strong>\u00bb, e la cineconversazione,&nbsp;moderata dalla dott.ssa Teresa Cona, si \u00e8 voluto mettere in risalto la legge che il cristianesimo ha impiantato in Europa come un ideale e una missione: la legge di solidariet\u00e0, di amore e di unit\u00e0 di tutta l&#8217;umanit\u00e0. Questa legge, oggi minacciata, marginalizzata, disprezzata e addirittura rifiutata, erede del patrimonio biblico giudaico-cristiano, ci garantisce comunque che, di fronte alla diversit\u00e0 di persone e culture, religioni e popoli, tutti gli uomini sono fratelli e sorelle, come costantemente ce lo ricorda anche frate Francesco d&#8217;Assisi, nel suo \u00abCantico delle creature\u00bb. Questo \u00e8 ci\u00f2 che dice la Bibbia nei suoi capitoli iniziali. La nozione che l&#8217;uomo \u00e8 creato a immagine di Dio rappresenta la base della dignit\u00e0 incondizionata e universale di ogni persona umana. Si tratta della dignit\u00e0 che non ci pu\u00f2 essere mai tolta: n\u00e9 per la cattiva condotta, n\u00e9 per la disabilit\u00e0, n\u00e9 per la differenza religiosa, etnica o di genere.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5262\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/Stol-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Guardando l&#8217;intenso film di Sollima \u2013 uno spaccato di realt\u00e0 che getta una luce cruda su un mondo in cui oppressori ed oppressi, carnefici e vittime, si scambiano rapidamente i ruoli e vengono osservati da un punto di vista che esclude pregiudizi e stereotipi, scandagliando in profondit\u00e0 la psiche dei protagonisti e le problematiche di una societ\u00e0 orfana di regole e abbandonata all&#8217;insicurezza e all&#8217;anarchia \u2212 per certi versi ci siamo sentiti posti sul banco degli imputati. Spessissime volte anche noi siamo oppressivi e persecutori. Eppure professiamo un Dio uno e trino, antidoto alla violenza e causa di riconciliazione, manifestazione in Cristo di un amore che non cerca il dominio, ma rende per sempre contraddittoria la violenza tra gli uomini. Crediamo in un Dio che \u00e8 comunione, unione, amore. Pace e nonviolenza sono parte integrante e decisiva del nostro credo cristiano. Fortunatamente sono rari i cattolici che vorrebbero armarsi contro un nemico. C&#8217;\u00e8 tuttavia una violenza pi\u00f9 sottile e pi\u00f9 diffusa, quella fatta di parole, di atteggiamenti, di modi di relazionarsi. \u00c8 quella a cui fa riferimento Papa Francesco quando dice di evitare il proselitismo, l&#8217;ingerenza spirituale, la costruzione di muri di risentimento, di odio e di vendetta&#8230;<\/p>\n<p style=\"text-align: justify;\">Una Serata indimenticabile, &#8216;non aggressiva&#8217;, &#8216;non violenta&#8217;, ma &#8216;pacifica&#8217;, mite, tenera, nel giorno in cui il Papa&nbsp;ha ricevuto in udienza i funzionari, gli agenti e il personale civile della Polizia di Stato, incitandoli&nbsp;ad avere \u00abcoraggio, mitezza e tenerezza\u00bb.<\/p>\n<p style=\"text-align: right;\"><em>Piotr Anzulewicz OFMConv<\/em><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-5244 gallery-columns-2 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2-103x77.jpg 103w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/4b62a208-05f9-45bd-b2d7-fadbd8c100d2.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6383\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6383-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6392\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6392-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6391\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6391-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6397\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6397-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6401\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6401-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6393\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6393-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6386\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6386-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695-103x77.jpg 103w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/8b0303b2-c9e5-4c5f-8e7e-0ed6f455a695.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6389\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6389-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6400\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6400-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa-103x77.jpg 103w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/bd3f1ddf-b60c-43bb-a608-adc0bdc797aa.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6390\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6390-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/208571c8-0e01-44a0-a50c-39fea0b557e1\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1-103x77.jpg 103w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/208571c8-0e01-44a0-a50c-39fea0b557e1.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6402\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6402-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/circoloculturalesanfrancesco.org\/site\/vibrava-lideale-della-nonviolenza\/img_6406\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-300x225.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-300x225.jpg 300w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-768x576.jpg 768w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-1024x768.jpg 1024w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-100x75.jpg 100w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/IMG_6406-103x77.jpg 103w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>In ogni scelta non dobbiamo mai lasciarci guidare dalla logica della violenza, e neppure da quella del taglione, cio\u00e8 dell&#8217;\u00abocchio per occhio\u00bb e \u00abdente per dente\u00bb. Non ne hanno avuto dubbi i presenti alla&#46;&#46;&#46;<\/p>\n","protected":false},"author":8,"featured_media":5265,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[48,8,32],"tags":[43,94,59,215,133],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>...vibrava l&#039;ideale della nonviolenza -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"...vibrava l&#039;ideale della nonviolenza -\" \/>\n<meta property=\"og:description\" content=\"In ogni scelta non dobbiamo mai lasciarci guidare dalla logica della violenza, e neppure da quella del taglione, cio\u00e8 dell&#8217;\u00abocchio per occhio\u00bb e \u00abdente per dente\u00bb. Non ne hanno avuto dubbi i presenti alla&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-26T22:25:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-27T08:42:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#website\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg\",\"contentUrl\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg\",\"width\":900,\"height\":622},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#webpage\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/\",\"name\":\"...vibrava l'ideale della nonviolenza -\",\"isPartOf\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#primaryimage\"},\"datePublished\":\"2018-05-26T22:25:31+00:00\",\"dateModified\":\"2018-05-27T08:42:07+00:00\",\"author\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2\"},\"breadcrumb\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8230;vibrava l&#8217;ideale della nonviolenza\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/www.circoloculturalesanfrancesco.org\",\"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/\"],\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/author\/panzulewicz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"...vibrava l'ideale della nonviolenza -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/","og_locale":"it_IT","og_type":"article","og_title":"...vibrava l'ideale della nonviolenza -","og_description":"In ogni scelta non dobbiamo mai lasciarci guidare dalla logica della violenza, e neppure da quella del taglione, cio\u00e8 dell&#8217;\u00abocchio per occhio\u00bb e \u00abdente per dente\u00bb. Non ne hanno avuto dubbi i presenti alla&#46;&#46;&#46;","og_url":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/","article_author":"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/","article_published_time":"2018-05-26T22:25:31+00:00","article_modified_time":"2018-05-27T08:42:07+00:00","og_image":[{"width":900,"height":622,"url":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg","type":"image\/jpeg"}],"twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#website","url":"https:\/\/circoloculturalesanfrancesco.org\/site\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circoloculturalesanfrancesco.org\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg","contentUrl":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2018\/05\/18759-1.jpg","width":900,"height":622},{"@type":"WebPage","@id":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#webpage","url":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/","name":"...vibrava l'ideale della nonviolenza -","isPartOf":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#primaryimage"},"datePublished":"2018-05-26T22:25:31+00:00","dateModified":"2018-05-27T08:42:07+00:00","author":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2"},"breadcrumb":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/circoloculturalesanfrancesco.org\/vibrava-lideale-della-nonviolenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circoloculturalesanfrancesco.org\/site\/"},{"@type":"ListItem","position":2,"name":"&#8230;vibrava l&#8217;ideale della nonviolenza"}]},{"@type":"Person","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g","caption":"admin"},"sameAs":["http:\/\/www.circoloculturalesanfrancesco.org","https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/"],"url":"https:\/\/circoloculturalesanfrancesco.org\/site\/author\/panzulewicz\/"}]}},"_links":{"self":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/5244"}],"collection":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":4,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/5244\/revisions"}],"predecessor-version":[{"id":5267,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/5244\/revisions\/5267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/media\/5265"}],"wp:attachment":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/media?parent=5244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/categories?post=5244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/tags?post=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}