{"id":2782,"date":"2016-02-02T00:20:09","date_gmt":"2016-02-01T23:20:09","guid":{"rendered":"http:\/\/circoloculturalesanfrancesco.org\/?p=2782"},"modified":"2016-02-02T11:33:39","modified_gmt":"2016-02-02T10:33:39","slug":"e-partita-anche-la-2a-edizione-del-cinecircolo","status":"publish","type":"post","link":"https:\/\/circoloculturalesanfrancesco.org\/site\/e-partita-anche-la-2a-edizione-del-cinecircolo\/","title":{"rendered":"\u00c8 partita anche la 2\u00aa edizione del CineCircolo"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/2782?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Visualizza PDF\" \/><\/a><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/2782?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Stampa contenuto\" \/><\/a><\/div><p style=\"text-align: justify;\">Venerd\u00ec 29 gennaio il Circolo ha lanciato la <strong>2\u00aa edizione del <em>Cine<\/em>Circolo<\/strong>, un\u2019iniziativa originale e interessante, \u00ab<strong>sui sentieri della misericordia<\/strong>\u00bb, focalizzata sulla triade: accoglienza\u2013integrazione\u2013viaggi della speranza, con il cinedibattito a conclusione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/11\/Calabria-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2386\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/11\/Calabria-1-150x150.jpg\" alt=\"Calabria 1\" width=\"150\" height=\"150\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/11\/Calabria-1-150x150.jpg 150w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/11\/Calabria-1-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>In una cultura, che sempre pi\u00f9 si configura come cultura della spettacolarit\u00e0 generalizzata, il CineCircolo, nella sua <strong>1\u00aa edizione<\/strong>, con il ciclo \u00ab<strong>Calabria mon amour<\/strong>\u00bb, ha presentato pellicole su temi-storie ambientate sul territorio calabrese, per rendere conoscibile un patrimonio cinematografico legato direttamente ai paesi, alle citt\u00e0 e ai luoghi che, ospitando i set, le troupe e i cast, sono diventati famosi, o ai personaggi del cinema, di nascita o di famiglia calabrese, che si sono fatti conoscere in tutto il mondo. Cos\u00ec gli spettatori hanno avuto l\u2019occasione di \u00abcomprendere meglio \u2013 leggiamo sul pieghevole \u2013 la nostra storia, la nostra cultura e le nostre tradizioni, apprezzarne la bont\u00e0 e comunicare la bellezza, attraverso il coinvolgimento personale, la prossimit\u00e0 e il dialogo, sulle strade digitali del nostro mondo contemporaneo, affollate di umanit\u00e0, spesso ferita: uomini e donne che cercano una salvezza o una speranza\u00bb. Durante il cinedibattito, che seguiva ogni proiezione del film, potevano reimparare ad ascoltare, comunicare e fruttificare, nella prossimit\u00e0 e in modo inclusivo, rispettoso e costruttivo, favorendo uno sguardo d\u2019insieme. \u00c8 stato un \u00abomaggio alla terra di Calabria, spesse volte dimenticata e mai sufficientemente apprezzata per le infinite qualit\u00e0 paesaggistiche, folcloristiche, faunistiche, culinarie, ed ai suoi abitanti\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/01\/Volantino-Doichlanda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2651\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/01\/Volantino-Doichlanda-150x150.jpg\" alt=\"Volantino - Doichlanda\" width=\"150\" height=\"150\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/01\/Volantino-Doichlanda-150x150.jpg 150w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/01\/Volantino-Doichlanda-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>La proiezione del film-documentario musicale \u00ab<strong>Doichlanda<\/strong>\u00bb di Giuseppe Gagliardi (per la recensione si veda ad esempio il link: <a href=\"http:\/\/www.mescalina.it\/musica\/recensioni\/il-parto-delle-nuvole-pesanti-doichlanda-dvd\">http:\/\/www.mescalina.it\/musica\/recensioni\/il-parto-delle-nuvole-pesanti-doichlanda-dvd<\/a>) ha segnato il lancio della 2\u00aa edizione del <em>Cine<\/em>Circolo. Tutti i film sono stati selezionati, con la preziosa consulenza di <strong>Eugenio Attanasio<\/strong>, regista e presidente della <strong>Cineteca della Calabria<\/strong>, nella prospettiva indicata da Papa Francesco nella Bolla di Indizione dell\u2019Anno giubilare, dal titolo \u00abMisericordiae vultus\u00bb (11 aprile 2015), per immergere gli spettatori nella dimensione di misericordia e di compassione, di perdono e di riconciliazione. Di pi\u00f9, con il cinedibattito, previsto anche questa volta alla fine della proiezione, dove ci si mette qualcosa di se stessi e dove non si \u00e8 pi\u00f9 spettatori passivi, ma attivi, viene offerto uno spazio per le tematiche come l\u2019<strong>accoglienza<\/strong>, l\u2019<strong>integrazione razziale<\/strong> e i <strong>viaggi della speranza<\/strong>. \u00abTutti \u2013 si legge sul d\u00e9pliant \u2013 abbiamo bisogno di metterci in discussione, senza avere mai paura dell\u2019inciampo, e di farci raccontare cosa sta succedendo. \u00c8 importante nell\u2019Anno della Misericordia andare oltre il senso di colpa e continuare a cercare delle vie d\u2019uscita, suggerite dalla fede, dal coraggio e dalla creativit\u00e0 dell\u2019uomo che da sempre ambisce alla felicit\u00e0. \u00c8 un momento straordinario per ritrovare i nostri fratelli pi\u00f9 fragili e riconoscerli come coloro che hanno bisogno di noi, che ci tendono le mani e che noi siamo nelle condizioni di poter soccorrerli e accoglierli\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il mondo crea lacerazioni ed \u00e8 solcato da scie d\u2019intolleranza, divisioni, violenze e guerre. Il cinema invece, questa moderna e fondamentale espressione dell\u2019arte, unisce popoli, culture e religioni. Per questo il <em>Cine<\/em>Circolo lo propone come luogo del dialogo e dell\u2019incontro, a cui attingere intimamente e intensamente. Quando poi esso s\u2019apre alla dimensione religiosa, toccando temi fortemente umani che hanno in s\u00e9 una carica trascendente, riesce a travalicare le diverse espressioni per giungere al cuore e alla mente dello spettatore.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/12\/IMG_1451.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2518\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/12\/IMG_1451-150x150.jpg\" alt=\"IMG_1451\" width=\"150\" height=\"150\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/12\/IMG_1451-150x150.jpg 150w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/12\/IMG_1451-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>Il curatore dell\u2019attuale edizione, la <strong>dott.ssa Teresa Cona<\/strong> \u2013 segretaria del Circolo, in collaborazione con l\u2019<strong>avv. Giuseppe Frontera<\/strong> e il <strong>M\u00b0 Luigi Cimino<\/strong> \u2013 membri del Consiglio direttivo, accogliendo queste indicazioni, cercher\u00e0 di invitare ospiti d\u2019eccezione per condividere la loro conoscenza ed esperienza relative alle tre tematiche sopraindicate. \u00abAbbeverandosi alla fonte della fratellanza, e prendendone ispirazione, ci aiuter\u00e0 a guarire le memorie dolorose, a costruire l&#8217;armonia, a far fiorire incontri umani fecondi. Al cuore della comunicazione vi \u00e8 soprattutto una profonda dimensione umana \u2013 comunicazione che non \u00e8 solo una tecnologia attuale o aggiornata, ma una profonda relazione interpersonale\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/03\/Donna1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1423\" src=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/03\/Donna1-150x150.jpg\" alt=\"Donna\" width=\"150\" height=\"150\" srcset=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/03\/Donna1-150x150.jpg 150w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/03\/Donna1-66x66.jpg 66w, https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2015\/03\/Donna1-78x77.jpg 78w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>La prima pellicola \u00abDoichlanda\u00bb ha offerto l\u2019opportunit\u00e0 di soffermarsi sull\u2019<strong>emigrazione calabrese<\/strong> e sui <strong>flussi migratori<\/strong> tra l\u2019Italia ed altri paesi, soprattutto europei. La serata era piuttosto fredda e solo in pochi hanno avuto il coraggio di venire alla proiezione. Ci dispiace di non disporre di una vera e propria <strong>sala cinematografica<\/strong>, riscaldata e attrezzata di poltrone. L\u2019attuale \u00e8 \u201cpovera\u201d, come fu povera s. Elisabetta d\u2019Ungheria a cui essa \u00e8 dedicata, e condivisa con l\u2019Ordine Francescano Secolare (OFS) e con la Giovent\u00f9 Francescana (Gi.Fra.). Nell\u2019ottobre scorso, grazie al parroco, p. Ilario Scali, si \u00e8 arricchita di un palco per l\u2019auspicata biblioteca francescana (al riguardo si legga: <a href=\"https:\/\/circoloculturalesanfrancesco.org\/site\/biblioteca-sognata-insieme\/\">https:\/\/circoloculturalesanfrancesco.org\/site\/biblioteca-sognata-insieme\/<\/a>) e di <strong>tende per le finestre<\/strong> localizzate in alto e al di fuori della manovrabilit\u00e0, che finora si doveva adombrare con i supporti in cartone, e nel gennaio di quest\u2019anno, grazie al Circolo, di due <strong>lampadari<\/strong> e di una <strong>plafoniera<\/strong> (ci servono altre tre o quattro da applicare alle pareti laterali). Per ogni evento affittiamo il<strong> service audiovisivo<\/strong> (grazie, Ghenadi, Luigi e Gabriele, per la vostra fatica nel portare, montare, gestire, smontare e portare via), il <strong>proiettore<\/strong> e lo <strong>schermo<\/strong>. Siamo poveri, e non ce ne vergogniamo, anzi, ne siamo francescanamente fieri. Il nostro <strong>budget<\/strong> \u00e8 quasi sempre in rosso, per cui siamo immensamente grati per ogni piccolo gesto di sostegno. Tra i nostri sogni costanti ci sono anche due essenziali strumenti: un <strong>computer<\/strong> e una <strong>stampante<\/strong> per la Segreteria.<\/p>\n<p style=\"text-align: justify;\">Siamo lieti di invitare tutti, vicini e lontani, a questa edizione. Per parteciparvi non bisogna acquistare il biglietto, perch\u00e9 l\u2019ingresso \u00e8 libero e gratuito. A conclusione c\u2019\u00e8 qualche delizia per il palato. Anch\u2019esso vuole la sua parte. A venerd\u00ec prossimo.<\/p>\n<p style=\"text-align: right;\"><em>Piotr Anzulewicz OFMConv<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 29 gennaio il Circolo ha lanciato la 2\u00aa edizione del CineCircolo, un\u2019iniziativa originale e interessante, \u00absui sentieri della misericordia\u00bb, focalizzata sulla triade: accoglienza\u2013integrazione\u2013viaggi della speranza, con il cinedibattito a conclusione. In una cultura,&#46;&#46;&#46;<\/p>\n","protected":false},"author":8,"featured_media":2783,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[48,8,32],"tags":[43,94,98,59,65,13],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c8 partita anche la 2\u00aa edizione del CineCircolo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c8 partita anche la 2\u00aa edizione del CineCircolo -\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 29 gennaio il Circolo ha lanciato la 2\u00aa edizione del CineCircolo, un\u2019iniziativa originale e interessante, \u00absui sentieri della misericordia\u00bb, focalizzata sulla triade: accoglienza\u2013integrazione\u2013viaggi della speranza, con il cinedibattito a conclusione. In una cultura,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-01T23:20:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-02T10:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#website\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg\",\"contentUrl\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg\",\"width\":276,\"height\":183},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#webpage\",\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/\",\"name\":\"\u00c8 partita anche la 2\u00aa edizione del CineCircolo -\",\"isPartOf\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#primaryimage\"},\"datePublished\":\"2016-02-01T23:20:09+00:00\",\"dateModified\":\"2016-02-02T10:33:39+00:00\",\"author\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2\"},\"breadcrumb\":{\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c8 partita anche la 2\u00aa edizione del CineCircolo\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/www.circoloculturalesanfrancesco.org\",\"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/\"],\"url\":\"https:\/\/circoloculturalesanfrancesco.org\/site\/author\/panzulewicz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c8 partita anche la 2\u00aa edizione del CineCircolo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/","og_locale":"it_IT","og_type":"article","og_title":"\u00c8 partita anche la 2\u00aa edizione del CineCircolo -","og_description":"Venerd\u00ec 29 gennaio il Circolo ha lanciato la 2\u00aa edizione del CineCircolo, un\u2019iniziativa originale e interessante, \u00absui sentieri della misericordia\u00bb, focalizzata sulla triade: accoglienza\u2013integrazione\u2013viaggi della speranza, con il cinedibattito a conclusione. In una cultura,&#46;&#46;&#46;","og_url":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/","article_author":"https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/","article_published_time":"2016-02-01T23:20:09+00:00","article_modified_time":"2016-02-02T10:33:39+00:00","og_image":[{"width":276,"height":183,"url":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg","type":"image\/jpeg"}],"twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#website","url":"https:\/\/circoloculturalesanfrancesco.org\/site\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circoloculturalesanfrancesco.org\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg","contentUrl":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-content\/uploads\/2016\/02\/Misericordia-piedi.jpg","width":276,"height":183},{"@type":"WebPage","@id":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#webpage","url":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/","name":"\u00c8 partita anche la 2\u00aa edizione del CineCircolo -","isPartOf":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#primaryimage"},"datePublished":"2016-02-01T23:20:09+00:00","dateModified":"2016-02-02T10:33:39+00:00","author":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2"},"breadcrumb":{"@id":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/circoloculturalesanfrancesco.org\/e-partita-anche-la-2a-edizione-del-cinecircolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circoloculturalesanfrancesco.org\/site\/"},{"@type":"ListItem","position":2,"name":"\u00c8 partita anche la 2\u00aa edizione del CineCircolo"}]},{"@type":"Person","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#\/schema\/person\/aaf2eff003877a067bad8f35656b0ec2","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/circoloculturalesanfrancesco.org\/site\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c528ef69a5e20c241fb0d2a3863e2fd?s=96&d=identicon&r=g","caption":"admin"},"sameAs":["http:\/\/www.circoloculturalesanfrancesco.org","https:\/\/www.facebook.com\/circoloculturalesanfrancescocatanzaro\/"],"url":"https:\/\/circoloculturalesanfrancesco.org\/site\/author\/panzulewicz\/"}]}},"_links":{"self":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/2782"}],"collection":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/comments?post=2782"}],"version-history":[{"count":4,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/2782\/revisions"}],"predecessor-version":[{"id":2788,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/posts\/2782\/revisions\/2788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/media?parent=2782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/categories?post=2782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circoloculturalesanfrancesco.org\/site\/wp-json\/wp\/v2\/tags?post=2782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}